{"id":2654,"date":"2022-05-29T22:16:55","date_gmt":"2022-05-29T20:16:55","guid":{"rendered":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/?p=2654"},"modified":"2022-06-09T22:14:00","modified_gmt":"2022-06-09T20:14:00","slug":"stop-making-sense","status":"publish","type":"post","link":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/2022\/05\/29\/stop-making-sense\/","title":{"rendered":"Stop making sense"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die \u00dcberschrift ist der Titel eines Musikfilms der Rockgruppe &#8222;Talking Heads&#8220;, einer Band, die ich fr\u00fcher sehr gerne geh\u00f6rt habe. Warum ich ihn aufgegriffen habe, dazu komme ich sp\u00e4ter in diesem Beitrag zur\u00fcck.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Affekt-Vorhersagen<\/strong>: Wir Menschen liegen oft meilenweit daneben, wenn wir einsch\u00e4tzen sollen, ob und wie lange uns ein zuk\u00fcnftiges Ereignis gl\u00fccklich bzw. ungl\u00fccklich machen wird. Wenn wir satt sind, untersch\u00e4tzen wir unseren Appetit am n\u00e4chsten Morgen, wenn wir hungrig einkaufen gehen, \u00fcbersch\u00e4tzen wir unseren tats\u00e4chlichen Bedarf an Lebensmitteln.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Drogens\u00fcchtige untersch\u00e4tzen regelm\u00e4\u00dfig ihr sp\u00e4teres Verlangen nach der Droge, wenn sie sie gerade konsumiert haben und man \u00fcbersch\u00e4tzt, wie ungl\u00fccklich man zwei Monate nach einer K\u00fcndigung sein wird.<\/p>\n\n\n\n<script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5111369003353249\" crossorigin=\"anonymous\"><\/script>\n<!-- 1blog1.2 -->\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:640px;height:90px\" data-ad-client=\"ca-pub-5111369003353249\" data-ad-slot=\"1908720896\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Warum gibt es diesen Effekt?<\/strong> Es gibt dazu zwei L\u00f6sungsans\u00e4tze. Der erste ist, dass wir \u00fcbersch\u00e4tzen, wie lange oder wie intensiv wir zuk\u00fcnftig \u00fcber das Ereignis nachdenken werden. Das liegt daran, dass wir momentan unsere Aufmerksamkeit eben auf dieses eine zuk\u00fcnftige Ereignis lenken. Im Arbeitsged\u00e4chtnis ist wenig Platz, ca. 1 bis 4 Punkte k\u00f6nnen wir damit maximal verarbeiten, insofern kann man sich vorstellen, dass man total vernachl\u00e4ssigt, was man denken wird, wenn das Ereignis eingetroffen ist. Nehmen wir einmal an, wir stellen uns vor, wie wir uns freuen w\u00fcrden, wenn Deutschland die WM gewinnt. Die Freude ist meist k\u00fcrzer als man denkt, bald treten andere Inhalte ins Arbeitsged\u00e4chtnis: Das Auto ist kaputt, man hat Stress bei der Arbeit, die Frist bis zur Pr\u00fcfungsvorleistung im Studium l\u00e4uft ab usw.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der zweite Ansatz ist der, dass wir unser Verm\u00f6gen untersch\u00e4tzen, uns &#8222;einen Reim&#8220; auf eine Sache zu machen, also wie wir ein Ereignis nachtr\u00e4glich interpretieren. Hier kommt das &#8222;Sensemaking&#8220; ins Spiel, was man mit &#8222;Sinnfindung&#8220; \u00fcbersetzen k\u00f6nnte. Das bedeutet, dass man im Nachhinein einen Sinn in dem Geschehenen sieht oder konstruiert, sodass dieses irgendwie erkl\u00e4rbar wird.<\/p>\n\n\n\n<script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5111369003353249\" crossorigin=\"anonymous\"><\/script>\n<!-- 1blog1.2 -->\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:640px;height:90px\" data-ad-client=\"ca-pub-5111369003353249\" data-ad-slot=\"1908720896\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sensemaking:<\/strong> Sensemaking hat nicht unbedingt etwas mit Schicksalsgl\u00e4ubigkeit zu tun, ebenso kann es sein, dass man etwas ganz neutral als Gl\u00fcck oder Pech bezeichnet. Dann sucht man quasi das Gl\u00fcck im Ungl\u00fcck. Beispielsweise denkt man sich nach einem Unfall, dass z.B. die Familie nun wieder enger zusammen w\u00e4chst; dass der Unfall eben Dinge nach sich zieht, die das Leben wieder zu einer koh\u00e4renten, in sich stimmigen Sache machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nehmen wir einmal an, ich w\u00fcrde dir einen Euro schenken. Was glaubst du, w\u00fcrde dich f\u00fcnf Minuten sp\u00e4ter gl\u00fccklicher machen? Wenn ich dir sagen w\u00fcrde, warum du ihn bekommen hast, oder wenn ich dir den Grund nicht sage? Es gibt ein psychologisches Experiment dazu. Die meisten sagten, sie w\u00fcrden gl\u00fccklicher sein, wenn sie den Grund w\u00fc\u00dften, tats\u00e4chlich war es aber genau umgekehrt. Die gr\u00f6\u00dfere Freude entsteht also, wenn Sensemaking-Prozesse aktiv sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sensenmaking verl\u00e4uft gr\u00f6\u00dftenteils unbewusst:<\/strong> Der Prozess des Sensemaking vollzieht  sich gr\u00f6\u00dftenteis au\u00dferhalb unseres Bewusstseins. D.h., wir finden oder erfinden den Sinn eines Ereignisses ohne bewusst dar\u00fcber nachzudenken. W\u00fcrden wir es absichtlich, d.h. bewusst machen, beispielsweise wenn wir uns einreden, dass der Expartner sowieso h\u00e4sslich und strohdumm gewesen ist, um besser \u00fcber die Trennung hinwegzukommen, dann klappt es nicht. <\/p>\n\n\n\n<script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5111369003353249\" crossorigin=\"anonymous\"><\/script>\n<!-- 1blog1.2 -->\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:640px;height:90px\" data-ad-client=\"ca-pub-5111369003353249\" data-ad-slot=\"1908720896\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Stop making sense? <\/strong>Die unbewusste Maschinerie l\u00e4sst sich nicht stoppen. Sie liefert uns im Nachhinein Gr\u00fcnde, warum etwas so oder so geschehen ist. Aus der Sicht eines Evolutionsbiologen hat diese Sinnfindung nat\u00fcrlich einen Sinn, sie sch\u00fctzt uns vor Verzweiflung und Hoffnungslosigkeit (was wiederum ein Beispiel f\u00fcr Sensemaking ist). Andererseits muss man sich bewusst machen, dass uns unser Gehirn unbewusst etwas vormacht, aber das ist ein infiniter Regress, es sei denn, man kann sich Unbewusstes bewusst machen, und das ist wohl eher (k)ein Problem f\u00fcr die Nachfolger von Sigmund Freud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die \u00dcberschrift ist der Titel eines Musikfilms der Rockgruppe &#8222;Talking Heads&#8220;, einer Band, die ich fr\u00fcher sehr gerne geh\u00f6rt habe. Warum ich ihn aufgegriffen habe, dazu komme ich sp\u00e4ter in diesem Beitrag zur\u00fcck. Affekt-Vorhersagen: Wir Menschen liegen oft meilenweit daneben, &hellip; <a href=\"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/2022\/05\/29\/stop-making-sense\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30],"tags":[],"class_list":["post-2654","post","type-post","status-publish","format-standard","hentry","category-psychologie"],"_links":{"self":[{"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/posts\/2654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/comments?post=2654"}],"version-history":[{"count":11,"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/posts\/2654\/revisions"}],"predecessor-version":[{"id":2672,"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/posts\/2654\/revisions\/2672"}],"wp:attachment":[{"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/media?parent=2654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/categories?post=2654"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/tags?post=2654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}