{"id":2668,"date":"2022-06-09T22:12:39","date_gmt":"2022-06-09T20:12:39","guid":{"rendered":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/?p=2668"},"modified":"2022-07-10T20:20:18","modified_gmt":"2022-07-10T18:20:18","slug":"mettendchen-ohne-gruenkohl-und-sowas","status":"publish","type":"post","link":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/2022\/06\/09\/mettendchen-ohne-gruenkohl-und-sowas\/","title":{"rendered":"Mettendchen ohne Gr\u00fcnkohl und sowas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Als Student geht man ja schon ganz gerne mal nach 20.00 Uhr zum Aldi oder sonstwohin um ein oder ein paar Schn\u00e4ppchen zu machen, besonders in der heutigen Zeit, wo alles jeden Tag stetig teurer wird. Besonders im K\u00fchlregal wird man oft f\u00fcndig, da gibt es h\u00e4ufig Artikel, die das Mhd bald erreicht haben und deshalb besonders g\u00fcnstig sind, gestern z.B. gab es Mettendchen, vier St\u00fcck f\u00fcr einen Euro, das hat sich gelohnt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<!--more-->\n\n\n\n<script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5111369003353249\" crossorigin=\"anonymous\"><\/script>\n<!-- 1blog1.2 -->\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:640px;height:90px\" data-ad-client=\"ca-pub-5111369003353249\" data-ad-slot=\"1908720896\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber was macht man so mit Mettentchen, sorry, Mettendchen? Die meisten kann man roh essen, doch auf der R\u00fcckseite fand sich der Hinweis, dass man die W\u00fcrstchen nur gut durcherhitzt verzehren sollte. Als experimentierfreudiger Mensch habe ich sie also in Scheiben geschnippelt und angebraten. Ich dachte mir, das passt ganz gut zu Kartoffelsalat, den hatte ich noch da, aber lasst es lieber, die W\u00fcrstchen werden total bitter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ich vermute, das liegt an den Gew\u00fcrzen darin, die darf man wohl nicht anbraten. Ich meine, erlaubt ist das nat\u00fcrlich, aber es schmeckt wirklich pfui. Nun, Hunger treibt&#8217;s hinein, aber ich hatte noch zwei Endchen \u00fcbrig, die wollte ich mir nicht verderben. Also habe ich sie einfach in kochendem Wasser erhitzt. Man sollte sie in leicht kochendes Wasser geben, wenn es sprudelnd kocht, belieben sie zu platzen. Dann den Herd runterschalten, 10 min. ziehen lassen und anrichten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<script async=\"\" src=\"https:\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js?client=ca-pub-5111369003353249\" crossorigin=\"anonymous\"><\/script>\n<!-- 1blog1.2 -->\n<ins class=\"adsbygoogle\" style=\"display:inline-block;width:640px;height:90px\" data-ad-client=\"ca-pub-5111369003353249\" data-ad-slot=\"1908720896\"><\/ins>\n<script>\n     (adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anrichten klingt etwas abgehoben, aber mit Senf schmecken sie wirklich lecker. Wer m\u00f6chte, kann sie in ein Toastbrot einwickeln, in den Senf tauchen und herzhaft hineinbei\u00dfen. Ich h\u00e4tte mir einen Vorrat mitnehmen sollen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als Student geht man ja schon ganz gerne mal nach 20.00 Uhr zum Aldi oder sonstwohin um ein oder ein paar Schn\u00e4ppchen zu machen, besonders in der heutigen Zeit, wo alles jeden Tag stetig teurer wird. Besonders im K\u00fchlregal wird &hellip; <a href=\"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/2022\/06\/09\/mettendchen-ohne-gruenkohl-und-sowas\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[],"class_list":["post-2668","post","type-post","status-publish","format-standard","hentry","category-essen-und-trinken"],"_links":{"self":[{"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/posts\/2668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/comments?post=2668"}],"version-history":[{"count":6,"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/posts\/2668\/revisions"}],"predecessor-version":[{"id":2730,"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/posts\/2668\/revisions\/2730"}],"wp:attachment":[{"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/media?parent=2668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/categories?post=2668"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/flora-emslandia.de\/wildpflanzen-blog\/wp-json\/wp\/v2\/tags?post=2668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}